{"id":7824,"date":"2015-12-11T20:50:48","date_gmt":"2015-12-11T20:50:48","guid":{"rendered":"http:\/\/www.fieam.org.br\/site\/sesi\/?p=7823"},"modified":"2015-12-11T20:50:48","modified_gmt":"2015-12-11T20:50:48","slug":"torneio-de-robotica-reune-400-alunos-da-regiao-norte","status":"publish","type":"post","link":"https:\/\/fieam.org.br\/sesi\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\/","title":{"rendered":"Torneio de Rob\u00f3tica re\u00fane 400 alunos da regi\u00e3o norte"},"content":{"rendered":"<figure id=\"attachment_7826\" aria-describedby=\"caption-attachment-7826\" style=\"width: 614px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.fieam.org.br\/site\/sesi\/files\/2015\/12\/Juizes-dao-as-boas-vindas-com-o-famoso-Hifi-aos-competidores.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-7826 \" alt=\"Ju\u00edzes d\u00e3o as boas vindas com o famoso Hifi aos competidores.jpg\" src=\"http:\/\/www.fieam.org.br\/site\/sesi\/files\/2015\/12\/Juizes-dao-as-boas-vindas-com-o-famoso-Hifi-aos-competidores.jpg\" width=\"614\" height=\"410\" \/><\/a><figcaption id=\"caption-attachment-7826\" class=\"wp-caption-text\">Ju\u00edzes d\u00e3o as boas vindas com o famoso Hifi aos competidores.jpg<\/figcaption><\/figure>\n<p>Pelo menos 38 equipes, formadas por alunos entre 9 e 16 anos de idade, de escolas p\u00fablicas e particulares da Regi\u00e3o Norte, competem at\u00e9 este s\u00e1bado, 12, na etapa Regional do Torneio de Rob\u00f3tica First Lego League (FLL) 2015, realizado no Clube do Trabalhador. O torneio acontece em Manaus com a coordena\u00e7\u00e3o do\u00a0<a href=\"http:\/\/www.fieam.org.br\/sesi\" target=\"_blank\" rel=\"noreferrer noopener\">Servi\u00e7o Social da Ind\u00fastria (SESI\/AM).<\/a><\/p>\n<p>As equipes deram um show de carisma e comprometimento na abertura oficial, organizando os chamados \u201cPits\u201d, locais de apresenta\u00e7\u00e3o dos projetos e na prepara\u00e7\u00e3o para as competi\u00e7\u00f5es da etapa \u201cDesign do Rob\u00f4\u201d, na qual os alunos colocam em pr\u00e1tica conhecimentos t\u00e9cnicos antes realizados apenas no computador e que agora s\u00e3o apresentados em tr\u00eas \u201cRounds\u201d, sendo avaliados o design mec\u00e2nico, programa\u00e7\u00e3o, estrat\u00e9gia e inova\u00e7\u00e3o, e desempenho do rob\u00f4 em mesa.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_7824\" aria-describedby=\"caption-attachment-7824\" style=\"width: 614px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.fieam.org.br\/site\/sesi\/files\/2015\/12\/Competidores-empolgados-para-a-disputa-do-torneio-regional.jpg\"><img decoding=\"async\" class=\" wp-image-7824 \" alt=\"Competidores empolgados para a disputa do torneio regional\" src=\"http:\/\/www.fieam.org.br\/site\/sesi\/files\/2015\/12\/Competidores-empolgados-para-a-disputa-do-torneio-regional.jpg\" width=\"614\" height=\"410\" \/><\/a><figcaption id=\"caption-attachment-7824\" class=\"wp-caption-text\">Competidores empolgados para a disputa do torneio regional<\/figcaption><\/figure>\n<p>\u201c\u00c9 uma honra sediar mais uma vez o torneio de rob\u00f3tica em nossa cidade, estamos sempre de bra\u00e7os abertos, apoiando a educa\u00e7\u00e3o e principalmente o futuro do nosso pa\u00eds\u201d, disse a diretora t\u00e9cnica do SESI Amazonas, Rosana Vasconcelos.<\/p>\n<p><a href=\"http:\/\/www.fieam.org.br\/senai\" target=\"_blank\" rel=\"noreferrer noopener\">O Servi\u00e7o Nacional de Aprendizagem Industrial (SENAI Amazonas)<\/a>\u00a0tamb\u00e9m participa da competi\u00e7\u00e3o com a equipe Esas Bot, formada por alunos do curso de Aprendizagem Industrial da Escola SENAI Ant\u00f4nio Sim\u00f5es (ESAS), no curso Assistente Administrativo.<\/p>\n<p>Para Priscila Rodrigues, t\u00e9cnica da equipe e instrutora da ESAS, os desafios j\u00e1 come\u00e7aram antes para os alunos da escola, principalmente pela pouca experi\u00eancia da equipe na \u00e1rea eletr\u00f4nica. A equipe levou para a competi\u00e7\u00e3o o projeto inovador \u201cLixeira eletr\u00f4nica\u201d com jogos direcionados a alunos do ensino fundamental para auxiliar professores em mat\u00e9rias, como Portugu\u00eas e Meio Ambiente.<\/p>\n<figure id=\"attachment_7825\" aria-describedby=\"caption-attachment-7825\" style=\"width: 410px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.fieam.org.br\/site\/sesi\/files\/2015\/12\/Equipe-ESAS-Bot-do-SENAI-aceitou-o-desafio-e-veio-com-o-projeto-Lixo-Eletronico.jpg\"><img decoding=\"async\" class=\" wp-image-7825 \" alt=\"Equipe ESAS Bot do SENAI aceitou o desafio e veio com o projeto Lixo Eletronico\" src=\"http:\/\/www.fieam.org.br\/site\/sesi\/files\/2015\/12\/Equipe-ESAS-Bot-do-SENAI-aceitou-o-desafio-e-veio-com-o-projeto-Lixo-Eletronico.jpg\" width=\"410\" height=\"614\" \/><\/a><figcaption id=\"caption-attachment-7825\" class=\"wp-caption-text\">Equipe ESAS Bot do SENAI aceitou o desafio e veio com o projeto Lixo Eletronico<\/figcaption><\/figure>\n<p>\u201cAs lixeiras eletr\u00f4nicas foram adaptadas de acordo com as cores de descarte de cada res\u00edduo, trabalhando com as ferramentas dispon\u00edveis na Escola SENAI. \u00c9 desafiador para n\u00f3s competirmos com esses alunos, mas a experi\u00eancia \u00e9 o que fica\u201d, disse Priscila.<\/p>\n<p>O SESI Amazonas participa do torneio com 22 equipes formadas por alunos das Escolas SESI Dra. Emina Barbosa Mustafa, SESI Dr. Adalberto Ferreira do Valle, SESI Abrah\u00e3o Sabb\u00e1 (Itacoatiara), SESI David N\u00f3voa (Iranduba) e SESI Padre Francisco Luppino (Parintins).\u00a0 Tamb\u00e9m participam equipes dos Estados de Rond\u00f4nia e Amap\u00e1. Os\u00a0cinco primeiros colocados no Torneio de Rob\u00f3tica ganham vaga para\u00a0 participar da fase nacional que ser\u00e1 realizada em Bras\u00edlia, em mar\u00e7o de 2016.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pelo menos 38 equipes, formadas por alunos entre 9 e 16 anos de idade, de escolas p\u00fablicas e particulares da Regi\u00e3o Norte, competem at\u00e9 este s\u00e1bado, 12, na etapa Regional do Torneio de Rob\u00f3tica First Lego League (FLL) 2015, realizado no Clube do Trabalhador. O torneio acontece em Manaus com a coordena\u00e7\u00e3o do\u00a0Servi\u00e7o Social da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-7824","post","type-post","status-publish","format-standard","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Torneio de Rob\u00f3tica re\u00fane 400 alunos da regi\u00e3o norte - SESI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fieam.org.br\/sesi\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Torneio de Rob\u00f3tica re\u00fane 400 alunos da regi\u00e3o norte - SESI\" \/>\n<meta property=\"og:description\" content=\"Pelo menos 38 equipes, formadas por alunos entre 9 e 16 anos de idade, de escolas p\u00fablicas e particulares da Regi\u00e3o Norte, competem at\u00e9 este s\u00e1bado, 12, na etapa Regional do Torneio de Rob\u00f3tica First Lego League (FLL) 2015, realizado no Clube do Trabalhador. O torneio acontece em Manaus com a coordena\u00e7\u00e3o do\u00a0Servi\u00e7o Social da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fieam.org.br\/sesi\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\/\" \/>\n<meta property=\"og:site_name\" content=\"SESI\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-11T20:50:48+00:00\" \/>\n<meta name=\"author\" content=\"Autor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\\\/\"},\"author\":{\"name\":\"Autor\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#\\\/schema\\\/person\\\/f54998dd14d5f0695b41444f2b01c31e\"},\"headline\":\"Torneio de Rob\u00f3tica re\u00fane 400 alunos da regi\u00e3o norte\",\"datePublished\":\"2015-12-11T20:50:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\\\/\"},\"wordCount\":481,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.fieam.org.br\\\/site\\\/sesi\\\/files\\\/2015\\\/12\\\/Juizes-dao-as-boas-vindas-com-o-famoso-Hifi-aos-competidores.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\\\/\",\"url\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\\\/\",\"name\":\"Torneio de Rob\u00f3tica re\u00fane 400 alunos da regi\u00e3o norte - SESI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.fieam.org.br\\\/site\\\/sesi\\\/files\\\/2015\\\/12\\\/Juizes-dao-as-boas-vindas-com-o-famoso-Hifi-aos-competidores.jpg\",\"datePublished\":\"2015-12-11T20:50:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.fieam.org.br\\\/site\\\/sesi\\\/files\\\/2015\\\/12\\\/Juizes-dao-as-boas-vindas-com-o-famoso-Hifi-aos-competidores.jpg\",\"contentUrl\":\"http:\\\/\\\/www.fieam.org.br\\\/site\\\/sesi\\\/files\\\/2015\\\/12\\\/Juizes-dao-as-boas-vindas-com-o-famoso-Hifi-aos-competidores.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Torneio de Rob\u00f3tica re\u00fane 400 alunos da regi\u00e3o norte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#website\",\"url\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/\",\"name\":\"SESI\",\"description\":\"Site Oficial!\",\"publisher\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#organization\",\"name\":\"SESI\",\"url\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/03\\\/cropped-fav.png\",\"contentUrl\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/03\\\/cropped-fav.png\",\"width\":610,\"height\":589,\"caption\":\"SESI\"},\"image\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#\\\/schema\\\/person\\\/f54998dd14d5f0695b41444f2b01c31e\",\"name\":\"Autor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g\",\"caption\":\"Autor\"},\"sameAs\":[\"https:\\\/\\\/marketingmassivo.com.br\"],\"url\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Torneio de Rob\u00f3tica re\u00fane 400 alunos da regi\u00e3o norte - SESI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fieam.org.br\/sesi\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\/","og_locale":"pt_BR","og_type":"article","og_title":"Torneio de Rob\u00f3tica re\u00fane 400 alunos da regi\u00e3o norte - SESI","og_description":"Pelo menos 38 equipes, formadas por alunos entre 9 e 16 anos de idade, de escolas p\u00fablicas e particulares da Regi\u00e3o Norte, competem at\u00e9 este s\u00e1bado, 12, na etapa Regional do Torneio de Rob\u00f3tica First Lego League (FLL) 2015, realizado no Clube do Trabalhador. O torneio acontece em Manaus com a coordena\u00e7\u00e3o do\u00a0Servi\u00e7o Social da [&hellip;]","og_url":"https:\/\/fieam.org.br\/sesi\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\/","og_site_name":"SESI","article_published_time":"2015-12-11T20:50:48+00:00","author":"Autor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Autor","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fieam.org.br\/sesi\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\/#article","isPartOf":{"@id":"https:\/\/fieam.org.br\/sesi\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\/"},"author":{"name":"Autor","@id":"https:\/\/fieam.org.br\/sesi\/#\/schema\/person\/f54998dd14d5f0695b41444f2b01c31e"},"headline":"Torneio de Rob\u00f3tica re\u00fane 400 alunos da regi\u00e3o norte","datePublished":"2015-12-11T20:50:48+00:00","mainEntityOfPage":{"@id":"https:\/\/fieam.org.br\/sesi\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\/"},"wordCount":481,"commentCount":0,"publisher":{"@id":"https:\/\/fieam.org.br\/sesi\/#organization"},"image":{"@id":"https:\/\/fieam.org.br\/sesi\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\/#primaryimage"},"thumbnailUrl":"http:\/\/www.fieam.org.br\/site\/sesi\/files\/2015\/12\/Juizes-dao-as-boas-vindas-com-o-famoso-Hifi-aos-competidores.jpg","articleSection":["News"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fieam.org.br\/sesi\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fieam.org.br\/sesi\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\/","url":"https:\/\/fieam.org.br\/sesi\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\/","name":"Torneio de Rob\u00f3tica re\u00fane 400 alunos da regi\u00e3o norte - SESI","isPartOf":{"@id":"https:\/\/fieam.org.br\/sesi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fieam.org.br\/sesi\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\/#primaryimage"},"image":{"@id":"https:\/\/fieam.org.br\/sesi\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\/#primaryimage"},"thumbnailUrl":"http:\/\/www.fieam.org.br\/site\/sesi\/files\/2015\/12\/Juizes-dao-as-boas-vindas-com-o-famoso-Hifi-aos-competidores.jpg","datePublished":"2015-12-11T20:50:48+00:00","breadcrumb":{"@id":"https:\/\/fieam.org.br\/sesi\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fieam.org.br\/sesi\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fieam.org.br\/sesi\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\/#primaryimage","url":"http:\/\/www.fieam.org.br\/site\/sesi\/files\/2015\/12\/Juizes-dao-as-boas-vindas-com-o-famoso-Hifi-aos-competidores.jpg","contentUrl":"http:\/\/www.fieam.org.br\/site\/sesi\/files\/2015\/12\/Juizes-dao-as-boas-vindas-com-o-famoso-Hifi-aos-competidores.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/fieam.org.br\/sesi\/torneio-de-robotica-reune-400-alunos-da-regiao-norte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/fieam.org.br\/sesi\/"},{"@type":"ListItem","position":2,"name":"Torneio de Rob\u00f3tica re\u00fane 400 alunos da regi\u00e3o norte"}]},{"@type":"WebSite","@id":"https:\/\/fieam.org.br\/sesi\/#website","url":"https:\/\/fieam.org.br\/sesi\/","name":"SESI","description":"Site Oficial!","publisher":{"@id":"https:\/\/fieam.org.br\/sesi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fieam.org.br\/sesi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/fieam.org.br\/sesi\/#organization","name":"SESI","url":"https:\/\/fieam.org.br\/sesi\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fieam.org.br\/sesi\/#\/schema\/logo\/image\/","url":"https:\/\/fieam.org.br\/sesi\/wp-content\/uploads\/sites\/14\/2024\/03\/cropped-fav.png","contentUrl":"https:\/\/fieam.org.br\/sesi\/wp-content\/uploads\/sites\/14\/2024\/03\/cropped-fav.png","width":610,"height":589,"caption":"SESI"},"image":{"@id":"https:\/\/fieam.org.br\/sesi\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fieam.org.br\/sesi\/#\/schema\/person\/f54998dd14d5f0695b41444f2b01c31e","name":"Autor","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g","caption":"Autor"},"sameAs":["https:\/\/marketingmassivo.com.br"],"url":"https:\/\/fieam.org.br\/sesi\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/posts\/7824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/comments?post=7824"}],"version-history":[{"count":0,"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/posts\/7824\/revisions"}],"wp:attachment":[{"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/media?parent=7824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/categories?post=7824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/tags?post=7824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}