{"id":5649,"date":"2014-07-01T20:28:18","date_gmt":"2014-07-01T20:28:18","guid":{"rendered":"http:\/\/www.fieam.org.br\/site\/sesi\/?p=5649"},"modified":"2014-07-01T20:28:18","modified_gmt":"2014-07-01T20:28:18","slug":"alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo","status":"publish","type":"post","link":"https:\/\/fieam.org.br\/sesi\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\/","title":{"rendered":"Alunos do SESI\/SENAI t\u00eam aulas de ingl\u00eas com m\u00e9todo novo"},"content":{"rendered":"<figure id=\"attachment_5650\" aria-describedby=\"caption-attachment-5650\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.fieam.org.br\/site\/sesi\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\/vinte-e-nove-alunos-do-sesi-e-senai-participam-da-primeira-edicao-do-cenexao-mundo-no-am\/\" rel=\"attachment wp-att-5650\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-5650\" alt=\"Vinte e nove alunos do SESI e SENAI participam da primeira edi\u00e7\u00e3o do Cenex\u00e3o Mundo no AM\" src=\"http:\/\/www.fieam.org.br\/2015\/sesi\/wp-content\/uploads\/sites\/2\/2014\/07\/Vinte-e-nove-alunos-do-SESI-e-SENAI-participam-da-primeira-edi\u00e7\u00e3o-do-Cenex\u00e3o-Mundo-no-AM-300x188.jpg\" width=\"300\" height=\"188\" \/><\/a><figcaption id=\"caption-attachment-5650\" class=\"wp-caption-text\">Vinte e nove alunos do SESI e SENAI participam da primeira edi\u00e7\u00e3o do Cenex\u00e3o Mundo no AM<\/figcaption><\/figure>\n<p>Um grupo de 30 estudantes de Manaus conclui no pr\u00f3ximo dia 8 (ter\u00e7a-feira), a segunda e mais importante etapa do Programa Conex\u00e3o Mundo, um curso de ingl\u00eas com m\u00e9todo diferenciado voltado para estudantes da Rede Nacional\u00a0<a href=\"http:\/\/www.fieam.org.br\/site\/sesi\" target=\"_blank\" rel=\"noopener\">SESI<\/a>\/<a href=\"http:\/\/www.fieam.org.br\/site\/senai\" target=\"_blank\" rel=\"noopener\">SENAI<\/a>\u00a0e escolas p\u00fablicas de todo o pa\u00eds, oferecido por meio de parceria com a organiza\u00e7\u00e3o n\u00e3o-governamental US-Brazil Connect. Os amazonenses s\u00e3o alunos do EBEP, modalidade que alia a educa\u00e7\u00e3o b\u00e1sica do SESI \u00e0 educa\u00e7\u00e3o profissional oferecida pelo SENAI.<\/p>\n<p>Com carga hor\u00e1ria de 340 horas, o Conex\u00e3o Mundo teve in\u00edcio em abril deste ano, no Amazonas, quando 64 estudantes disputaram as 30 vagas do primeiro edital do programa, coordenado pelo\u00a0<a href=\"http:\/\/www.fieam.org.br\/site\/fieam\" target=\"_blank\" rel=\"noopener\">Sistema Federa\u00e7\u00e3o das Ind\u00fastrias do Estado do Amazonas (FIEAM)<\/a>. O curso de ingl\u00eas, assim como o pr\u00f3prio EBEP, \u00e9 gratuito e contempla etapas a dist\u00e2ncia e presencial.<\/p>\n<p>A primeira e a \u00faltima etapa s\u00e3o desenvolvidas ao longo de oito semanas e demandam dedica\u00e7\u00e3o de 10 horas semanais on-line \u00e0s atividades aplicadas por monitores dos Estados Unidos por meio de ferramentas como facebook e hangouts, al\u00e9m de 100 horas na plataforma educacional Longman.<\/p>\n<p>De acordo com a coordenadora e supervisora pedag\u00f3gica do Programa, Luana da Silva, a segunda etapa, presencial, est\u00e1 sendo conclu\u00edda nesta semana. \u201cA programa\u00e7\u00e3o presencial vem sendo ministrada por tr\u00eas monitoras norte-americanas que trabalham com grupos de 10 alunos. Durante 20 dias \u00fateis, os estudantes percebem que o ingl\u00eas \u00e9 uma l\u00edngua que pode ser aprendida atrav\u00e9s da conex\u00e3o com a internet e aprimorada com professoras americanas. A fase de intera\u00e7\u00e3o com as monitoras em sala de aula estimula os jovens a se interessarem cada vez mais pelo ingl\u00eas\u201d, explica Luana de Freitas.<\/p>\n<p>Para a aluna do curso de assistente administrativo industrial, Mariana Freire, de 15 anos, participar do programa a incentivou a retornar ao curso de idiomas. A jovem cursou durante um m\u00eas aulas de ingl\u00eas, mas a lenta proposta do m\u00e9todo ent\u00e3o proposto a fez desistir.<\/p>\n<p>Com habilidades de comunica\u00e7\u00e3o b\u00e1sica adquiridas pelo contato on-line e presencial com os professores americanos, Mariana tem uma nova vis\u00e3o da import\u00e2ncia do ingl\u00eas e est\u00e1 firme no objetivo de concluir tanto o curso r\u00e1pido do Conex\u00e3o Mundo quanto o de longa dura\u00e7\u00e3o.<\/p>\n<p>\u201cTive uma experi\u00eancia melhor com o ingl\u00eas neste programa, pois al\u00e9m do curso b\u00e1sico, onde se aprende a escrever, pude exercitar a pronuncia com nativos. Hoje consigo entender muitas palavras e frases inteiras e isso est\u00e1 trazendo um resultado bom na escola de idiomas\u201d, disse Mariana.<\/p>\n<p>Com a perspectiva de logo entrar no mercado de trabalho, Tiago Carmin, de 16 anos, quer agregar ao seu curr\u00edculo a op\u00e7\u00e3o do ingl\u00eas fluente e para isso vem se esfor\u00e7ando ao m\u00e1ximo na programa\u00e7\u00e3o do Conex\u00e3o Mundo. O aluno lembra que sua experi\u00eancia com o ingl\u00eas vem do ensino m\u00e9dio convencional e pela internet.<\/p>\n<p>\u201cSempre pensei no meu futuro, na minha carreira profissional, por isso mesmo tenho consci\u00eancia de que o ingl\u00eas \u00e9 um idioma que abre portas para bons empregos. Confesso que \u00e9 um aprendizado n\u00e3o t\u00e3o f\u00e1cil, mas como sou curioso, sempre tento estudar pela internet, e, agora, com as professoras americanas. Todo esse esfor\u00e7o vem se tornando gratificante\u201d, avalia o aluno, destacando que se fosse lhe dada a op\u00e7\u00e3o de novamente escolher entre f\u00e9rias e as aulas de ingl\u00eas com o grupo do Conex\u00e3o Mundo, escolheria novamente o aprendizado, pois far\u00e1 a diferen\u00e7a na busca pelo primeiro emprego.<\/p>\n<p>Os melhores alunos do grupo de 30 v\u00e3o concorrer a uma vaga para participar de interc\u00e2mbio nos Estados Unidos com dura\u00e7\u00e3o de um m\u00eas. No total, ser\u00e3o 100 alunos dos 27 Departamentos Regionais do SESI e SENAI. Segundo a coordenadora do Conex\u00e3o Mundo no Amazonas, em 2015 o Regional dever\u00e1 aumentar o n\u00famero de vagas neste programa, passando para 48 alunos. O processo de sele\u00e7\u00e3o seguir\u00e1 o calend\u00e1rio deste ano, com abertura somente para alunos do EBEP, no m\u00eas de abril.<\/p>\n<p><b>\u00a0<\/b><\/p>\n<p><b>Aprendizado m\u00fatuo<\/b><\/p>\n<p><b><i>\u00a0<\/i><\/b><\/p>\n<p>Pela primeira vez no Brasil, a professora Sarah Ozee, de 46 anos, est\u00e1 maravilhada com o programa Conex\u00e3o Mundo e com o entusiasmo dos alunos em compreender o ingl\u00eas e em falar essa l\u00edngua que predomina nas rela\u00e7\u00f5es internacionais.<\/p>\n<p>\u201cEstou criando rela\u00e7\u00f5es com os alunos amazonenses, tendo a chance de passar conhecimentos sobre o ingl\u00eas. Levarei daqui um pouco do Brasil aos meus alunos dos Estados Unidos e mais experi\u00eancia nesta a\u00e7\u00e3o de ensinar jovens\u201d, destacou a professora l\u00edder desta primeira turma do Conex\u00e3o Mundo no Amazonas.<\/p>\n<p>A universit\u00e1ria Sandra de la Riva, de 22 anos, deve se despedir do programa em Manaus, pois quando retornar aos Estados Unidos, finalizar\u00e1 seu curso de rela\u00e7\u00f5es internacionais e l\u00ednguas. Sandra j\u00e1 realizou a programa\u00e7\u00e3o presencial do Conex\u00e3o nas cidades de Salvador (BA) e Macap\u00e1 (AP), contribuindo com o aprendizado do ingl\u00eas para 400 alunos.<\/p>\n<p>\u201cMeu trabalho \u00e9 de facilitar o ensino da l\u00edngua inglesa para brasileiros e ao realizar essa atividade, tamb\u00e9m ganho conex\u00e3o permanente. Por onde passo, tento ajudar de alguma forma, n\u00e3o s\u00f3 com a interpreta\u00e7\u00e3o e a fala do ingl\u00eas, mas tamb\u00e9m com o crescimento dos meus alunos\u201d, disse Sandra de la Riva.<\/p>\n<p>[nggallery id=248]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um grupo de 30 estudantes de Manaus conclui no pr\u00f3ximo dia 8 (ter\u00e7a-feira), a segunda e mais importante etapa do Programa Conex\u00e3o Mundo, um curso de ingl\u00eas com m\u00e9todo diferenciado voltado para estudantes da Rede Nacional\u00a0SESI\/SENAI\u00a0e escolas p\u00fablicas de todo o pa\u00eds, oferecido por meio de parceria com a organiza\u00e7\u00e3o n\u00e3o-governamental US-Brazil Connect. Os amazonenses [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-5649","post","type-post","status-publish","format-standard","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alunos do SESI\/SENAI t\u00eam aulas de ingl\u00eas com m\u00e9todo novo - SESI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fieam.org.br\/sesi\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alunos do SESI\/SENAI t\u00eam aulas de ingl\u00eas com m\u00e9todo novo - SESI\" \/>\n<meta property=\"og:description\" content=\"Um grupo de 30 estudantes de Manaus conclui no pr\u00f3ximo dia 8 (ter\u00e7a-feira), a segunda e mais importante etapa do Programa Conex\u00e3o Mundo, um curso de ingl\u00eas com m\u00e9todo diferenciado voltado para estudantes da Rede Nacional\u00a0SESI\/SENAI\u00a0e escolas p\u00fablicas de todo o pa\u00eds, oferecido por meio de parceria com a organiza\u00e7\u00e3o n\u00e3o-governamental US-Brazil Connect. Os amazonenses [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fieam.org.br\/sesi\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\/\" \/>\n<meta property=\"og:site_name\" content=\"SESI\" \/>\n<meta property=\"article:published_time\" content=\"2014-07-01T20:28:18+00:00\" \/>\n<meta name=\"author\" content=\"Autor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\\\/\"},\"author\":{\"name\":\"Autor\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#\\\/schema\\\/person\\\/f54998dd14d5f0695b41444f2b01c31e\"},\"headline\":\"Alunos do SESI\\\/SENAI t\u00eam aulas de ingl\u00eas com m\u00e9todo novo\",\"datePublished\":\"2014-07-01T20:28:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\\\/\"},\"wordCount\":957,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#organization\"},\"articleSection\":[\"News\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\\\/\",\"url\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\\\/\",\"name\":\"Alunos do SESI\\\/SENAI t\u00eam aulas de ingl\u00eas com m\u00e9todo novo - SESI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#website\"},\"datePublished\":\"2014-07-01T20:28:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alunos do SESI\\\/SENAI t\u00eam aulas de ingl\u00eas com m\u00e9todo novo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#website\",\"url\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/\",\"name\":\"SESI\",\"description\":\"Site Oficial!\",\"publisher\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#organization\",\"name\":\"SESI\",\"url\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/03\\\/cropped-fav.png\",\"contentUrl\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/03\\\/cropped-fav.png\",\"width\":610,\"height\":589,\"caption\":\"SESI\"},\"image\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#\\\/schema\\\/person\\\/f54998dd14d5f0695b41444f2b01c31e\",\"name\":\"Autor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g\",\"caption\":\"Autor\"},\"sameAs\":[\"https:\\\/\\\/marketingmassivo.com.br\"],\"url\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alunos do SESI\/SENAI t\u00eam aulas de ingl\u00eas com m\u00e9todo novo - SESI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fieam.org.br\/sesi\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\/","og_locale":"pt_BR","og_type":"article","og_title":"Alunos do SESI\/SENAI t\u00eam aulas de ingl\u00eas com m\u00e9todo novo - SESI","og_description":"Um grupo de 30 estudantes de Manaus conclui no pr\u00f3ximo dia 8 (ter\u00e7a-feira), a segunda e mais importante etapa do Programa Conex\u00e3o Mundo, um curso de ingl\u00eas com m\u00e9todo diferenciado voltado para estudantes da Rede Nacional\u00a0SESI\/SENAI\u00a0e escolas p\u00fablicas de todo o pa\u00eds, oferecido por meio de parceria com a organiza\u00e7\u00e3o n\u00e3o-governamental US-Brazil Connect. Os amazonenses [&hellip;]","og_url":"https:\/\/fieam.org.br\/sesi\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\/","og_site_name":"SESI","article_published_time":"2014-07-01T20:28:18+00:00","author":"Autor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Autor","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fieam.org.br\/sesi\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\/#article","isPartOf":{"@id":"https:\/\/fieam.org.br\/sesi\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\/"},"author":{"name":"Autor","@id":"https:\/\/fieam.org.br\/sesi\/#\/schema\/person\/f54998dd14d5f0695b41444f2b01c31e"},"headline":"Alunos do SESI\/SENAI t\u00eam aulas de ingl\u00eas com m\u00e9todo novo","datePublished":"2014-07-01T20:28:18+00:00","mainEntityOfPage":{"@id":"https:\/\/fieam.org.br\/sesi\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\/"},"wordCount":957,"commentCount":0,"publisher":{"@id":"https:\/\/fieam.org.br\/sesi\/#organization"},"articleSection":["News"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fieam.org.br\/sesi\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fieam.org.br\/sesi\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\/","url":"https:\/\/fieam.org.br\/sesi\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\/","name":"Alunos do SESI\/SENAI t\u00eam aulas de ingl\u00eas com m\u00e9todo novo - SESI","isPartOf":{"@id":"https:\/\/fieam.org.br\/sesi\/#website"},"datePublished":"2014-07-01T20:28:18+00:00","breadcrumb":{"@id":"https:\/\/fieam.org.br\/sesi\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fieam.org.br\/sesi\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fieam.org.br\/sesi\/alunos-do-sesisenai-tem-aulas-de-ingles-com-metodo-novo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/fieam.org.br\/sesi\/"},{"@type":"ListItem","position":2,"name":"Alunos do SESI\/SENAI t\u00eam aulas de ingl\u00eas com m\u00e9todo novo"}]},{"@type":"WebSite","@id":"https:\/\/fieam.org.br\/sesi\/#website","url":"https:\/\/fieam.org.br\/sesi\/","name":"SESI","description":"Site Oficial!","publisher":{"@id":"https:\/\/fieam.org.br\/sesi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fieam.org.br\/sesi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/fieam.org.br\/sesi\/#organization","name":"SESI","url":"https:\/\/fieam.org.br\/sesi\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fieam.org.br\/sesi\/#\/schema\/logo\/image\/","url":"https:\/\/fieam.org.br\/sesi\/wp-content\/uploads\/sites\/14\/2024\/03\/cropped-fav.png","contentUrl":"https:\/\/fieam.org.br\/sesi\/wp-content\/uploads\/sites\/14\/2024\/03\/cropped-fav.png","width":610,"height":589,"caption":"SESI"},"image":{"@id":"https:\/\/fieam.org.br\/sesi\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fieam.org.br\/sesi\/#\/schema\/person\/f54998dd14d5f0695b41444f2b01c31e","name":"Autor","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g","caption":"Autor"},"sameAs":["https:\/\/marketingmassivo.com.br"],"url":"https:\/\/fieam.org.br\/sesi\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/posts\/5649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/comments?post=5649"}],"version-history":[{"count":0,"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/posts\/5649\/revisions"}],"wp:attachment":[{"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/media?parent=5649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/categories?post=5649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/tags?post=5649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}