{"id":3914,"date":"2013-02-06T14:02:46","date_gmt":"2013-02-06T14:02:46","guid":{"rendered":"http:\/\/www.fieam.org.br\/site\/sesi\/?p=3914"},"modified":"2013-02-06T14:02:46","modified_gmt":"2013-02-06T14:02:46","slug":"o-sesi-seleciona-talentos-5","status":"publish","type":"post","link":"https:\/\/fieam.org.br\/sesi\/o-sesi-seleciona-talentos-5\/","title":{"rendered":"O SESI seleciona talentos"},"content":{"rendered":"<p>O <b>SESI<\/b> seleciona talentos para atuar nas \u00e1reas abaixo solicitadas, com os seguintes perfis:<\/p>\n<p align=\"justify\"><b>Professor: 1 vaga\/Pr\u00e9-requisitos:<\/b> Gradua\u00e7\u00e3o completa em Qu\u00edmica, disponibilidade de hor\u00e1rio para ministrar aulas no Ensino M\u00e9dio nas unidades do SESI e\/ou empresas, de modo itinerante, doc\u00eancia na disciplina de forma\u00e7\u00e3o, preenchimento e organiza\u00e7\u00e3o de documentos acerca do trabalho docente\/pedag\u00f3gico, envolvimento nas atividades realizadas pelo SESI inter e extraclasse, habilidade para atuar em Educa\u00e7\u00e3o de Jovens e Adultos e experi\u00eancia de 6 meses comprovados na \u00e1rea.<\/p>\n<p align=\"justify\"><b>Professor: 1 vaga\/Pr\u00e9-requisitos:<\/b> Gradua\u00e7\u00e3o completa em Educa\u00e7\u00e3o Art\u00edstica, disponibilidade de hor\u00e1rio para ministrar aulas nas s\u00e9ries iniciais do Ensino Fundamental, nas unidades SESI e\/ou empresas, de modo itinerante, doc\u00eancia na disciplina de forma\u00e7\u00e3o, preenchimento e organiza\u00e7\u00e3o de documentos acerca do trabalho docente\/pedag\u00f3gico, envolvimento nas atividades realizadas pelo SESI inter e extraclasse, habilidade para atuar em Educa\u00e7\u00e3o de Jovens e Adultos e experi\u00eancia de 6 meses comprovados na \u00e1rea.<\/p>\n<p align=\"justify\"><b>Professor: 1 vaga\/Pr\u00e9-requisitos:<\/b> Gradua\u00e7\u00e3o completa em Biologia, disponibilidade de hor\u00e1rio para ministrar aulas no Ensino M\u00e9dio nas unidades do SESI e\/ou empresas, de modo itinerante, doc\u00eancia na disciplina de forma\u00e7\u00e3o, preenchimento e organiza\u00e7\u00e3o de documentos acerca do trabalho docente\/pedag\u00f3gico, envolvimento nas atividades realizadas pelo SESI inter e extraclasse, habilidade para atuar em Educa\u00e7\u00e3o de Jovens e Adultos e Experi\u00eancia de 6 meses comprovados na \u00e1rea.<\/p>\n<p align=\"justify\"><b>Professor: 1 vaga\/Pr\u00e9-requisitos:<\/b> Gradua\u00e7\u00e3o completa em F\u00edsica para ministrar e planejar aulas no Ensino M\u00e9dio, acompanhar alunos, participar de reuni\u00f5es pedag\u00f3gicas e demais atividades pertinentes ao cargo. Experi\u00eancia de 6 meses comprovados na \u00e1rea.<\/p>\n<p align=\"justify\"><b>Professor: 1 vaga \/ Pr\u00e9-requisitos:<\/b> Gradua\u00e7\u00e3o completa em Ci\u00eancias Biol\u00f3gicas para ministrar e planejar aulas no Ensino M\u00e9dio, acompanhar alunos, participar de reuni\u00f5es pedag\u00f3gicas e demais atividades pertinentes ao cargo. Experi\u00eancia de 6 meses comprovados na \u00e1rea.<\/p>\n<p align=\"justify\">Os interessados dever\u00e3o deixar o curr\u00edculo na recep\u00e7\u00e3o do Edif\u00edcio Raimar Aguiar, localizado na Avenida Joaquim Nabuco, 1919, no per\u00edodo de 4 a 8 de fevereiro de 2013. Informar no curr\u00edculo o cargo pretendido e e-mail.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O SESI seleciona talentos para atuar nas \u00e1reas abaixo solicitadas, com os seguintes perfis: Professor: 1 vaga\/Pr\u00e9-requisitos: Gradua\u00e7\u00e3o completa em Qu\u00edmica, disponibilidade de hor\u00e1rio para ministrar aulas no Ensino M\u00e9dio nas unidades do SESI e\/ou empresas, de modo itinerante, doc\u00eancia na disciplina de forma\u00e7\u00e3o, preenchimento e organiza\u00e7\u00e3o de documentos acerca do trabalho docente\/pedag\u00f3gico, envolvimento nas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3862,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-3914","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-selecao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O SESI seleciona talentos - SESI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fieam.org.br\/sesi\/o-sesi-seleciona-talentos-5\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O SESI seleciona talentos - SESI\" \/>\n<meta property=\"og:description\" content=\"O SESI seleciona talentos para atuar nas \u00e1reas abaixo solicitadas, com os seguintes perfis: Professor: 1 vaga\/Pr\u00e9-requisitos: Gradua\u00e7\u00e3o completa em Qu\u00edmica, disponibilidade de hor\u00e1rio para ministrar aulas no Ensino M\u00e9dio nas unidades do SESI e\/ou empresas, de modo itinerante, doc\u00eancia na disciplina de forma\u00e7\u00e3o, preenchimento e organiza\u00e7\u00e3o de documentos acerca do trabalho docente\/pedag\u00f3gico, envolvimento nas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fieam.org.br\/sesi\/o-sesi-seleciona-talentos-5\/\" \/>\n<meta property=\"og:site_name\" content=\"SESI\" \/>\n<meta property=\"article:published_time\" content=\"2013-02-06T14:02:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fieam.org.br\/sesi\/wp-content\/uploads\/sites\/14\/2013\/01\/selecao1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Autor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/o-sesi-seleciona-talentos-5\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/o-sesi-seleciona-talentos-5\\\/\"},\"author\":{\"name\":\"Autor\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#\\\/schema\\\/person\\\/f54998dd14d5f0695b41444f2b01c31e\"},\"headline\":\"O SESI seleciona talentos\",\"datePublished\":\"2013-02-06T14:02:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/o-sesi-seleciona-talentos-5\\\/\"},\"wordCount\":374,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/o-sesi-seleciona-talentos-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2013\\\/01\\\/selecao1.jpg\",\"articleSection\":[\"selecao\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/o-sesi-seleciona-talentos-5\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/o-sesi-seleciona-talentos-5\\\/\",\"url\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/o-sesi-seleciona-talentos-5\\\/\",\"name\":\"O SESI seleciona talentos - SESI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/o-sesi-seleciona-talentos-5\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/o-sesi-seleciona-talentos-5\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2013\\\/01\\\/selecao1.jpg\",\"datePublished\":\"2013-02-06T14:02:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/o-sesi-seleciona-talentos-5\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/o-sesi-seleciona-talentos-5\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/o-sesi-seleciona-talentos-5\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2013\\\/01\\\/selecao1.jpg\",\"contentUrl\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2013\\\/01\\\/selecao1.jpg\",\"width\":250,\"height\":250,\"caption\":\"Sele\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/o-sesi-seleciona-talentos-5\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O SESI seleciona talentos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#website\",\"url\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/\",\"name\":\"SESI\",\"description\":\"Site Oficial!\",\"publisher\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#organization\",\"name\":\"SESI\",\"url\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/03\\\/cropped-fav.png\",\"contentUrl\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/03\\\/cropped-fav.png\",\"width\":610,\"height\":589,\"caption\":\"SESI\"},\"image\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#\\\/schema\\\/person\\\/f54998dd14d5f0695b41444f2b01c31e\",\"name\":\"Autor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g\",\"caption\":\"Autor\"},\"sameAs\":[\"https:\\\/\\\/marketingmassivo.com.br\"],\"url\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O SESI seleciona talentos - SESI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fieam.org.br\/sesi\/o-sesi-seleciona-talentos-5\/","og_locale":"pt_BR","og_type":"article","og_title":"O SESI seleciona talentos - SESI","og_description":"O SESI seleciona talentos para atuar nas \u00e1reas abaixo solicitadas, com os seguintes perfis: Professor: 1 vaga\/Pr\u00e9-requisitos: Gradua\u00e7\u00e3o completa em Qu\u00edmica, disponibilidade de hor\u00e1rio para ministrar aulas no Ensino M\u00e9dio nas unidades do SESI e\/ou empresas, de modo itinerante, doc\u00eancia na disciplina de forma\u00e7\u00e3o, preenchimento e organiza\u00e7\u00e3o de documentos acerca do trabalho docente\/pedag\u00f3gico, envolvimento nas [&hellip;]","og_url":"https:\/\/fieam.org.br\/sesi\/o-sesi-seleciona-talentos-5\/","og_site_name":"SESI","article_published_time":"2013-02-06T14:02:46+00:00","og_image":[{"width":250,"height":250,"url":"https:\/\/fieam.org.br\/sesi\/wp-content\/uploads\/sites\/14\/2013\/01\/selecao1.jpg","type":"image\/jpeg"}],"author":"Autor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Autor","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fieam.org.br\/sesi\/o-sesi-seleciona-talentos-5\/#article","isPartOf":{"@id":"https:\/\/fieam.org.br\/sesi\/o-sesi-seleciona-talentos-5\/"},"author":{"name":"Autor","@id":"https:\/\/fieam.org.br\/sesi\/#\/schema\/person\/f54998dd14d5f0695b41444f2b01c31e"},"headline":"O SESI seleciona talentos","datePublished":"2013-02-06T14:02:46+00:00","mainEntityOfPage":{"@id":"https:\/\/fieam.org.br\/sesi\/o-sesi-seleciona-talentos-5\/"},"wordCount":374,"commentCount":0,"publisher":{"@id":"https:\/\/fieam.org.br\/sesi\/#organization"},"image":{"@id":"https:\/\/fieam.org.br\/sesi\/o-sesi-seleciona-talentos-5\/#primaryimage"},"thumbnailUrl":"https:\/\/fieam.org.br\/sesi\/wp-content\/uploads\/sites\/14\/2013\/01\/selecao1.jpg","articleSection":["selecao"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fieam.org.br\/sesi\/o-sesi-seleciona-talentos-5\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fieam.org.br\/sesi\/o-sesi-seleciona-talentos-5\/","url":"https:\/\/fieam.org.br\/sesi\/o-sesi-seleciona-talentos-5\/","name":"O SESI seleciona talentos - SESI","isPartOf":{"@id":"https:\/\/fieam.org.br\/sesi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fieam.org.br\/sesi\/o-sesi-seleciona-talentos-5\/#primaryimage"},"image":{"@id":"https:\/\/fieam.org.br\/sesi\/o-sesi-seleciona-talentos-5\/#primaryimage"},"thumbnailUrl":"https:\/\/fieam.org.br\/sesi\/wp-content\/uploads\/sites\/14\/2013\/01\/selecao1.jpg","datePublished":"2013-02-06T14:02:46+00:00","breadcrumb":{"@id":"https:\/\/fieam.org.br\/sesi\/o-sesi-seleciona-talentos-5\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fieam.org.br\/sesi\/o-sesi-seleciona-talentos-5\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fieam.org.br\/sesi\/o-sesi-seleciona-talentos-5\/#primaryimage","url":"https:\/\/fieam.org.br\/sesi\/wp-content\/uploads\/sites\/14\/2013\/01\/selecao1.jpg","contentUrl":"https:\/\/fieam.org.br\/sesi\/wp-content\/uploads\/sites\/14\/2013\/01\/selecao1.jpg","width":250,"height":250,"caption":"Sele\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/fieam.org.br\/sesi\/o-sesi-seleciona-talentos-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/fieam.org.br\/sesi\/"},{"@type":"ListItem","position":2,"name":"O SESI seleciona talentos"}]},{"@type":"WebSite","@id":"https:\/\/fieam.org.br\/sesi\/#website","url":"https:\/\/fieam.org.br\/sesi\/","name":"SESI","description":"Site Oficial!","publisher":{"@id":"https:\/\/fieam.org.br\/sesi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fieam.org.br\/sesi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/fieam.org.br\/sesi\/#organization","name":"SESI","url":"https:\/\/fieam.org.br\/sesi\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fieam.org.br\/sesi\/#\/schema\/logo\/image\/","url":"https:\/\/fieam.org.br\/sesi\/wp-content\/uploads\/sites\/14\/2024\/03\/cropped-fav.png","contentUrl":"https:\/\/fieam.org.br\/sesi\/wp-content\/uploads\/sites\/14\/2024\/03\/cropped-fav.png","width":610,"height":589,"caption":"SESI"},"image":{"@id":"https:\/\/fieam.org.br\/sesi\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fieam.org.br\/sesi\/#\/schema\/person\/f54998dd14d5f0695b41444f2b01c31e","name":"Autor","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g","caption":"Autor"},"sameAs":["https:\/\/marketingmassivo.com.br"],"url":"https:\/\/fieam.org.br\/sesi\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/posts\/3914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/comments?post=3914"}],"version-history":[{"count":0,"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/posts\/3914\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/media\/3862"}],"wp:attachment":[{"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/media?parent=3914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/categories?post=3914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/tags?post=3914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}