{"id":2150,"date":"2011-10-26T14:35:08","date_gmt":"2011-10-26T14:35:08","guid":{"rendered":"http:\/\/www.fieam.org.br\/site\/sesi\/?p=2150"},"modified":"2011-10-26T14:35:08","modified_gmt":"2011-10-26T14:35:08","slug":"representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil","status":"publish","type":"post","link":"https:\/\/fieam.org.br\/sesi\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\/","title":{"rendered":"Representantes de doze pa\u00edses conhecem o programa Cozinha Brasil"},"content":{"rendered":"<p>Nesta semana, representantes de doze pa\u00edses da \u00c1frica, Caribe, Am\u00e9ricas e \u00c1sia est\u00e3o em Bras\u00edlia para conhecer a metodologia do programa Cozinha Brasil, por meio uma parceria do Conselho Nacional do <a href=\"http:\/\/www.sesi.org.br\/portal\/main.jsp\" target=\"_blank\" rel=\"noopener\">SESI<\/a>, da <a href=\"http:\/\/www.cni.org.br\/portal\/\" target=\"_blank\" rel=\"noopener\">Confedera\u00e7\u00e3o Nacional da Ind\u00fastria (CNI)<\/a> e da <a href=\"http:\/\/www.abc.gov.br\/\" target=\"_blank\" rel=\"noopener\">Ag\u00eancia Brasileira de Coopera\u00e7\u00e3o (ABC).<\/a><\/p>\n<p>O curso de transfer\u00eancia de tecnologia \u00e9 resultado da apresenta\u00e7\u00e3o do programa durante o semin\u00e1rio Coopera\u00e7\u00e3o T\u00e9cnica Brasileira: Agricultura, Seguran\u00e7a Alimentar e Pol\u00edticas, realizado em junho deste ano pelo Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores (MRE), na It\u00e1lia.<\/p>\n<p>Egito, Belize, S\u00e3o Tom\u00e9 e Pr\u00edncipe, Timor Leste, Tanz\u00e2nia, Honduras, Ilhas Fiji, M\u00e9xico, Burundi, S\u00e3o Crist\u00f3v\u00e3o e Nevis, Granada e Sri-Lanka participam do evento, que acontece na sede da <a href=\"http:\/\/www.sistemafibra.org.br\/fibra\/\" target=\"_blank\" rel=\"noopener\">Federa\u00e7\u00e3o das ind\u00fastrias do Distrito Federal (FIBRA).<\/a><\/p>\n<p>O programa j\u00e1 \u00e9 desenvolvido no Uruguai e Mo\u00e7ambique, e est\u00e1 sendo implementado na Guatemala e em El Salvador. No Brasil, quase um milh\u00e3o de pessoas foram beneficiadas. Os cursos s\u00e3o ministrados nas unidades m\u00f3veis do SESI e divididos em duas modalidades: para a popula\u00e7\u00e3o, com 10 horas\/aula, e para profissionais da \u00e1rea de alimenta\u00e7\u00e3o, de 24 horas\/aula.<\/p>\n<p>O programa ensina a evitar o desperd\u00edcio aproveitando integralmente os alimentos, como caule, talos, cascas, folhas e sementes, aliando economia, qualidade e sabor. As receitas buscam respeitar as diversidades regionais e a utiliza\u00e7\u00e3o de alimentos t\u00edpicos de cada localidade.<\/p>\n<p>Al\u00e9m disso, os alunos recebem orienta\u00e7\u00f5es de higiene pessoal, m\u00e9todos de limpeza e manuseio de utens\u00edlios, m\u00e9todos ideais de congelamento e descongelamento de alimentos, sem a perda de nutrientes.<\/p>\n<p><strong>Impactos sociais do Cozinha Brasil \u2013 <\/strong>Em 2009, o SESI realizou uma pesquisa com 4.100 usu\u00e1rios para mensurar os impactos sociais, econ\u00f4micos e financeiros do programa. De acordo com o estudo, a maioria dos alunos que se inscreve nos cursos de educa\u00e7\u00e3o alimentar n\u00e3o possui o h\u00e1bito de utilizar cascas de frutas e de legumes na alimenta\u00e7\u00e3o (66%) ou de fazer refei\u00e7\u00f5es no pr\u00f3prio domic\u00edlio (58,58%).<\/p>\n<p><strong>Assessoria de Comunica\u00e7\u00e3o \u2013 Conselho Nacional do SESI<\/strong><br \/>\nContato: (61) 3217- 0746 \/ 0714 ou <a href=\"mailto:comunicacaocn@sesi.org.br\" target=\"_blank\" rel=\"noopener\">comunicacaocn@sesi.org.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta semana, representantes de doze pa\u00edses da \u00c1frica, Caribe, Am\u00e9ricas e \u00c1sia est\u00e3o em Bras\u00edlia para conhecer a metodologia do programa Cozinha Brasil, por meio uma parceria do Conselho Nacional do SESI, da Confedera\u00e7\u00e3o Nacional da Ind\u00fastria (CNI) e da Ag\u00eancia Brasileira de Coopera\u00e7\u00e3o (ABC). O curso de transfer\u00eancia de tecnologia \u00e9 resultado da apresenta\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-2150","post","type-post","status-publish","format-standard","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Representantes de doze pa\u00edses conhecem o programa Cozinha Brasil - SESI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fieam.org.br\/sesi\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Representantes de doze pa\u00edses conhecem o programa Cozinha Brasil - SESI\" \/>\n<meta property=\"og:description\" content=\"Nesta semana, representantes de doze pa\u00edses da \u00c1frica, Caribe, Am\u00e9ricas e \u00c1sia est\u00e3o em Bras\u00edlia para conhecer a metodologia do programa Cozinha Brasil, por meio uma parceria do Conselho Nacional do SESI, da Confedera\u00e7\u00e3o Nacional da Ind\u00fastria (CNI) e da Ag\u00eancia Brasileira de Coopera\u00e7\u00e3o (ABC). O curso de transfer\u00eancia de tecnologia \u00e9 resultado da apresenta\u00e7\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fieam.org.br\/sesi\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\/\" \/>\n<meta property=\"og:site_name\" content=\"SESI\" \/>\n<meta property=\"article:published_time\" content=\"2011-10-26T14:35:08+00:00\" \/>\n<meta name=\"author\" content=\"Autor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Autor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\\\/\"},\"author\":{\"name\":\"Autor\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#\\\/schema\\\/person\\\/f54998dd14d5f0695b41444f2b01c31e\"},\"headline\":\"Representantes de doze pa\u00edses conhecem o programa Cozinha Brasil\",\"datePublished\":\"2011-10-26T14:35:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\\\/\"},\"wordCount\":377,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#organization\"},\"articleSection\":[\"News\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\\\/\",\"url\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\\\/\",\"name\":\"Representantes de doze pa\u00edses conhecem o programa Cozinha Brasil - SESI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#website\"},\"datePublished\":\"2011-10-26T14:35:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Representantes de doze pa\u00edses conhecem o programa Cozinha Brasil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#website\",\"url\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/\",\"name\":\"SESI\",\"description\":\"Site Oficial!\",\"publisher\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#organization\",\"name\":\"SESI\",\"url\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/03\\\/cropped-fav.png\",\"contentUrl\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/03\\\/cropped-fav.png\",\"width\":610,\"height\":589,\"caption\":\"SESI\"},\"image\":{\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/#\\\/schema\\\/person\\\/f54998dd14d5f0695b41444f2b01c31e\",\"name\":\"Autor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g\",\"caption\":\"Autor\"},\"sameAs\":[\"https:\\\/\\\/marketingmassivo.com.br\"],\"url\":\"https:\\\/\\\/fieam.org.br\\\/sesi\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Representantes de doze pa\u00edses conhecem o programa Cozinha Brasil - SESI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fieam.org.br\/sesi\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\/","og_locale":"pt_BR","og_type":"article","og_title":"Representantes de doze pa\u00edses conhecem o programa Cozinha Brasil - SESI","og_description":"Nesta semana, representantes de doze pa\u00edses da \u00c1frica, Caribe, Am\u00e9ricas e \u00c1sia est\u00e3o em Bras\u00edlia para conhecer a metodologia do programa Cozinha Brasil, por meio uma parceria do Conselho Nacional do SESI, da Confedera\u00e7\u00e3o Nacional da Ind\u00fastria (CNI) e da Ag\u00eancia Brasileira de Coopera\u00e7\u00e3o (ABC). O curso de transfer\u00eancia de tecnologia \u00e9 resultado da apresenta\u00e7\u00e3o [&hellip;]","og_url":"https:\/\/fieam.org.br\/sesi\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\/","og_site_name":"SESI","article_published_time":"2011-10-26T14:35:08+00:00","author":"Autor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Autor","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fieam.org.br\/sesi\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\/#article","isPartOf":{"@id":"https:\/\/fieam.org.br\/sesi\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\/"},"author":{"name":"Autor","@id":"https:\/\/fieam.org.br\/sesi\/#\/schema\/person\/f54998dd14d5f0695b41444f2b01c31e"},"headline":"Representantes de doze pa\u00edses conhecem o programa Cozinha Brasil","datePublished":"2011-10-26T14:35:08+00:00","mainEntityOfPage":{"@id":"https:\/\/fieam.org.br\/sesi\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\/"},"wordCount":377,"commentCount":0,"publisher":{"@id":"https:\/\/fieam.org.br\/sesi\/#organization"},"articleSection":["News"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fieam.org.br\/sesi\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fieam.org.br\/sesi\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\/","url":"https:\/\/fieam.org.br\/sesi\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\/","name":"Representantes de doze pa\u00edses conhecem o programa Cozinha Brasil - SESI","isPartOf":{"@id":"https:\/\/fieam.org.br\/sesi\/#website"},"datePublished":"2011-10-26T14:35:08+00:00","breadcrumb":{"@id":"https:\/\/fieam.org.br\/sesi\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fieam.org.br\/sesi\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fieam.org.br\/sesi\/representantes-de-doze-paises-conhecem-o-programa-cozinha-brasil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/fieam.org.br\/sesi\/"},{"@type":"ListItem","position":2,"name":"Representantes de doze pa\u00edses conhecem o programa Cozinha Brasil"}]},{"@type":"WebSite","@id":"https:\/\/fieam.org.br\/sesi\/#website","url":"https:\/\/fieam.org.br\/sesi\/","name":"SESI","description":"Site Oficial!","publisher":{"@id":"https:\/\/fieam.org.br\/sesi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fieam.org.br\/sesi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/fieam.org.br\/sesi\/#organization","name":"SESI","url":"https:\/\/fieam.org.br\/sesi\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/fieam.org.br\/sesi\/#\/schema\/logo\/image\/","url":"https:\/\/fieam.org.br\/sesi\/wp-content\/uploads\/sites\/14\/2024\/03\/cropped-fav.png","contentUrl":"https:\/\/fieam.org.br\/sesi\/wp-content\/uploads\/sites\/14\/2024\/03\/cropped-fav.png","width":610,"height":589,"caption":"SESI"},"image":{"@id":"https:\/\/fieam.org.br\/sesi\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fieam.org.br\/sesi\/#\/schema\/person\/f54998dd14d5f0695b41444f2b01c31e","name":"Autor","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3732c223e0e1fad69062a8f770955c9068d37b055204f310a0be18d4069fe380?s=96&d=mm&r=g","caption":"Autor"},"sameAs":["https:\/\/marketingmassivo.com.br"],"url":"https:\/\/fieam.org.br\/sesi\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/posts\/2150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/comments?post=2150"}],"version-history":[{"count":0,"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/posts\/2150\/revisions"}],"wp:attachment":[{"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/media?parent=2150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/categories?post=2150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fieam.org.br\/sesi\/wp-json\/wp\/v2\/tags?post=2150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}